{"id":329419,"date":"2023-02-16T11:02:40","date_gmt":"2011-03-17T09:56:24","guid":{"rendered":""},"modified":"2025-09-03T19:10:48","modified_gmt":"2025-09-03T19:10:48","slug":"1379815-citroen-xsara-1999-turschlossmechanik-4-turig-rechts-vorne-9136j2","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/","title":{"rendered":"Citroen Xsara  T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne 1999 9136J2"},"content":{"rendered":"<p>T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne<\/p>\n","protected":false},"excerpt":{"rendered":"T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne","protected":false},"featured_media":963424,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[243,278],"product_tag":[],"class_list":{"0":"post-329419","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-citroen","7":"product_cat-xsara","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen Xsara T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne 1999 9136J2 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen Xsara T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne 1999 9136J2 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T19:10:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/02\/560e5512-65d0-4c89-98e4-f09b5b207a82-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/\",\"name\":\"Citroen Xsara T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne 1999 9136J2 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/560e5512-65d0-4c89-98e4-f09b5b207a82.jpg\",\"datePublished\":\"2011-03-17T09:56:24+00:00\",\"dateModified\":\"2025-09-03T19:10:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/560e5512-65d0-4c89-98e4-f09b5b207a82.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/560e5512-65d0-4c89-98e4-f09b5b207a82.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen Xsara T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne 1999 9136J2 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/","og_locale":"de_DE","og_type":"article","og_title":"Citroen Xsara T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne 1999 9136J2 | De Vos Onderdelen","og_description":"T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne","og_url":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-09-03T19:10:48+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/02\/560e5512-65d0-4c89-98e4-f09b5b207a82-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/","url":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/","name":"Citroen Xsara T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne 1999 9136J2 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/560e5512-65d0-4c89-98e4-f09b5b207a82.jpg","datePublished":"2011-03-17T09:56:24+00:00","dateModified":"2025-09-03T19:10:48+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/560e5512-65d0-4c89-98e4-f09b5b207a82.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/560e5512-65d0-4c89-98e4-f09b5b207a82.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/xsara\/1379815-turschlossmechanik-4-turig-rechts-vorne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"T\u00fcrschlossmechanik 4-t\u00fcrig rechts vorne"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/329419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/963424"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=329419"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=329419"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=329419"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=329419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}