{"id":3459323,"date":"2024-02-05T16:19:30","date_gmt":"2024-01-15T16:28:22","guid":{"rendered":""},"modified":"2024-03-21T13:50:49","modified_gmt":"2024-03-21T13:50:49","slug":"19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/","title":{"rendered":"Peugeot 208 1.2 Vti 12V PureTech 75 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2020 9831168080"},"content":{"rendered":"<p>Sto\u00dfd\u00e4mpferstrebe rechts vorne<\/p>\n","protected":false},"excerpt":{"rendered":"Sto\u00dfd\u00e4mpferstrebe rechts vorne","protected":false},"featured_media":3084549,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[296,306],"product_tag":[],"class_list":{"0":"post-3459323","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-peugeot","7":"product_cat-306","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 208 1.2 Vti 12V PureTech 75 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2020 9831168080 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 208 1.2 Vti 12V PureTech 75 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2020 9831168080 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Sto\u00dfd\u00e4mpferstrebe rechts vorne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T13:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/01\/f68452f7-a2ee-4dca-bb01-3119ec2df30b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/\",\"name\":\"Peugeot 208 1.2 Vti 12V PureTech 75 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2020 9831168080 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/01\/f68452f7-a2ee-4dca-bb01-3119ec2df30b.jpg\",\"datePublished\":\"2024-01-15T16:28:22+00:00\",\"dateModified\":\"2024-03-21T13:50:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/01\/f68452f7-a2ee-4dca-bb01-3119ec2df30b.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/01\/f68452f7-a2ee-4dca-bb01-3119ec2df30b.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sto\u00dfd\u00e4mpferstrebe rechts vorne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 208 1.2 Vti 12V PureTech 75 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2020 9831168080 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/","og_locale":"de_DE","og_type":"article","og_title":"Peugeot 208 1.2 Vti 12V PureTech 75 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2020 9831168080 | De Vos Onderdelen","og_description":"Sto\u00dfd\u00e4mpferstrebe rechts vorne","og_url":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2024-03-21T13:50:49+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/01\/f68452f7-a2ee-4dca-bb01-3119ec2df30b.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/","url":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/","name":"Peugeot 208 1.2 Vti 12V PureTech 75 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2020 9831168080 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/01\/f68452f7-a2ee-4dca-bb01-3119ec2df30b.jpg","datePublished":"2024-01-15T16:28:22+00:00","dateModified":"2024-03-21T13:50:49+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/01\/f68452f7-a2ee-4dca-bb01-3119ec2df30b.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/01\/f68452f7-a2ee-4dca-bb01-3119ec2df30b.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/19966210-peugeot-208-1-2-vti-12v-puretech-75-2020-stosdampferstrebe-rechts-vorne-9831168080\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Sto\u00dfd\u00e4mpferstrebe rechts vorne"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/3459323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/3084549"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=3459323"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=3459323"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=3459323"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=3459323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}