{"id":3495171,"date":"2024-05-02T10:30:13","date_gmt":"2024-05-02T10:01:27","guid":{"rendered":""},"modified":"2026-09-01T04:56:15","modified_gmt":"2026-09-01T04:56:15","slug":"20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/","title":{"rendered":"Citroen C3 1.2 Vti 12V PureTech Kamera Vorderseite 2019 1640245680-9828694780"},"content":{"rendered":"<p>Kamera Vorderseite<\/p>\n","protected":false},"excerpt":{"rendered":"Kamera Vorderseite","protected":false},"featured_media":3495595,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[243,251],"product_tag":[],"class_list":["post-3495171","product","type-product","status-publish","has-post-thumbnail","product_cat-citroen","product_cat-c3","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen C3 1.2 Vti 12V PureTech Kamera Vorderseite 2019 1640245680-9828694780 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen C3 1.2 Vti 12V PureTech Kamera Vorderseite 2019 1640245680-9828694780 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Kamera Vorderseite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T04:56:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/\",\"name\":\"Citroen C3 1.2 Vti 12V PureTech Kamera Vorderseite 2019 1640245680-9828694780 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/05\/d5e723c7-fff6-4387-911f-d6bbe81308ea.jpg\",\"datePublished\":\"2024-05-02T10:01:27+00:00\",\"dateModified\":\"2026-09-01T04:56:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/05\/d5e723c7-fff6-4387-911f-d6bbe81308ea.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/05\/d5e723c7-fff6-4387-911f-d6bbe81308ea.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kamera Vorderseite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen C3 1.2 Vti 12V PureTech Kamera Vorderseite 2019 1640245680-9828694780 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/","og_locale":"de_DE","og_type":"article","og_title":"Citroen C3 1.2 Vti 12V PureTech Kamera Vorderseite 2019 1640245680-9828694780 | De Vos Onderdelen","og_description":"Kamera Vorderseite","og_url":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2026-09-01T04:56:15+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/","url":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/","name":"Citroen C3 1.2 Vti 12V PureTech Kamera Vorderseite 2019 1640245680-9828694780 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/05\/d5e723c7-fff6-4387-911f-d6bbe81308ea.jpg","datePublished":"2024-05-02T10:01:27+00:00","dateModified":"2026-09-01T04:56:15+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/05\/d5e723c7-fff6-4387-911f-d6bbe81308ea.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/05\/d5e723c7-fff6-4387-911f-d6bbe81308ea.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20592504-citroen-c3-1-2-vti-12v-puretech-2019-kamera-vorderseite-1640245680-9828694780\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Kamera Vorderseite"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/3495171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/3495595"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=3495171"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=3495171"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=3495171"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=3495171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}