{"id":3520139,"date":"2024-07-08T22:25:57","date_gmt":"2024-07-08T20:49:12","guid":{"rendered":""},"modified":"2025-03-26T13:43:36","modified_gmt":"2025-03-26T13:43:36","slug":"20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/","title":{"rendered":"Citroen C5 Aircross 2.0 Blue HDI 180 Schmutzf\u00e4nger Leiste 2020 98168322XT"},"content":{"rendered":"<p>Schmutzf\u00e4nger Leiste Citroen C5 Aircross (A4\/AC\/AJ\/AR) 2.0 Blue HDI 180<\/p>\n","protected":false},"excerpt":{"rendered":"Schmutzf\u00e4nger Leiste Citroen C5 Aircross (A4\/AC\/AJ\/AR) 2.0 Blue HDI 180","protected":false},"featured_media":3521541,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[243,259],"product_tag":[],"class_list":{"0":"post-3520139","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-citroen","7":"product_cat-c5-aircross","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen C5 Aircross 2.0 Blue HDI 180 Schmutzf\u00e4nger Leiste 2020 98168322XT | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen C5 Aircross 2.0 Blue HDI 180 Schmutzf\u00e4nger Leiste 2020 98168322XT | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Schmutzf\u00e4nger Leiste Citroen C5 Aircross (A4\/AC\/AJ\/AR) 2.0 Blue HDI 180\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T13:43:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/\",\"name\":\"Citroen C5 Aircross 2.0 Blue HDI 180 Schmutzf\u00e4nger Leiste 2020 98168322XT | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/07\/17a620c9-513d-4baa-994c-7130a4aa62ca.jpg\",\"datePublished\":\"2024-07-08T20:49:12+00:00\",\"dateModified\":\"2025-03-26T13:43:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/07\/17a620c9-513d-4baa-994c-7130a4aa62ca.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/07\/17a620c9-513d-4baa-994c-7130a4aa62ca.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schmutzf\u00e4nger Leiste Citroen C5 Aircross (A4\/AC\/AJ\/AR) 2.0 Blue HDI 180\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen C5 Aircross 2.0 Blue HDI 180 Schmutzf\u00e4nger Leiste 2020 98168322XT | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/","og_locale":"de_DE","og_type":"article","og_title":"Citroen C5 Aircross 2.0 Blue HDI 180 Schmutzf\u00e4nger Leiste 2020 98168322XT | De Vos Onderdelen","og_description":"Schmutzf\u00e4nger Leiste Citroen C5 Aircross (A4\/AC\/AJ\/AR) 2.0 Blue HDI 180","og_url":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-03-26T13:43:36+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/","url":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/","name":"Citroen C5 Aircross 2.0 Blue HDI 180 Schmutzf\u00e4nger Leiste 2020 98168322XT | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/07\/17a620c9-513d-4baa-994c-7130a4aa62ca.jpg","datePublished":"2024-07-08T20:49:12+00:00","dateModified":"2025-03-26T13:43:36+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/07\/17a620c9-513d-4baa-994c-7130a4aa62ca.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/07\/17a620c9-513d-4baa-994c-7130a4aa62ca.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/20930501-citroen-c5-aircross-2-0-blue-hdi-180-2020-schmutzfanger-leiste-98168322xt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Schmutzf\u00e4nger Leiste Citroen C5 Aircross (A4\/AC\/AJ\/AR) 2.0 Blue HDI 180"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/3520139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/3521541"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=3520139"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=3520139"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=3520139"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=3520139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}