{"id":3542119,"date":"2024-09-12T04:29:19","date_gmt":"2024-09-11T21:17:09","guid":{"rendered":""},"modified":"2026-08-31T22:44:25","modified_gmt":"2026-08-31T22:44:25","slug":"21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/","title":{"rendered":"Citroen C3 1.2 Vti 12V PureTech Sto\u00dfd\u00e4mpferstrebe links vorne 2019 9811371280"},"content":{"rendered":"<p>Sto\u00dfd\u00e4mpferstrebe links vorne Citroen C3 (SX\/SW) 1.2 Vti 12V PureTech<\/p>\n","protected":false},"excerpt":{"rendered":"Sto\u00dfd\u00e4mpferstrebe links vorne Citroen C3 (SX\/SW) 1.2 Vti 12V PureTech","protected":false},"featured_media":3543282,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[243,251],"product_tag":[],"class_list":["post-3542119","product","type-product","status-publish","has-post-thumbnail","product_cat-citroen","product_cat-c3","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen C3 1.2 Vti 12V PureTech Sto\u00dfd\u00e4mpferstrebe links vorne 2019 9811371280 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen C3 1.2 Vti 12V PureTech Sto\u00dfd\u00e4mpferstrebe links vorne 2019 9811371280 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Sto\u00dfd\u00e4mpferstrebe links vorne Citroen C3 (SX\/SW) 1.2 Vti 12V PureTech\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T22:44:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/\",\"name\":\"Citroen C3 1.2 Vti 12V PureTech Sto\u00dfd\u00e4mpferstrebe links vorne 2019 9811371280 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/09\/35acca5f-4082-48d5-90bc-8bdd04803ff9.jpg\",\"datePublished\":\"2024-09-11T21:17:09+00:00\",\"dateModified\":\"2026-08-31T22:44:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/09\/35acca5f-4082-48d5-90bc-8bdd04803ff9.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/09\/35acca5f-4082-48d5-90bc-8bdd04803ff9.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sto\u00dfd\u00e4mpferstrebe links vorne Citroen C3 (SX\/SW) 1.2 Vti 12V PureTech\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen C3 1.2 Vti 12V PureTech Sto\u00dfd\u00e4mpferstrebe links vorne 2019 9811371280 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/","og_locale":"de_DE","og_type":"article","og_title":"Citroen C3 1.2 Vti 12V PureTech Sto\u00dfd\u00e4mpferstrebe links vorne 2019 9811371280 | De Vos Onderdelen","og_description":"Sto\u00dfd\u00e4mpferstrebe links vorne Citroen C3 (SX\/SW) 1.2 Vti 12V PureTech","og_url":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2026-08-31T22:44:25+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/","url":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/","name":"Citroen C3 1.2 Vti 12V PureTech Sto\u00dfd\u00e4mpferstrebe links vorne 2019 9811371280 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/09\/35acca5f-4082-48d5-90bc-8bdd04803ff9.jpg","datePublished":"2024-09-11T21:17:09+00:00","dateModified":"2026-08-31T22:44:25+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/09\/35acca5f-4082-48d5-90bc-8bdd04803ff9.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/09\/35acca5f-4082-48d5-90bc-8bdd04803ff9.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/21234298-citroen-c3-1-2-vti-12v-puretech-2019-stosdampferstrebe-links-vorne-9811371280\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Sto\u00dfd\u00e4mpferstrebe links vorne Citroen C3 (SX\/SW) 1.2 Vti 12V PureTech"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/3542119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/3543282"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=3542119"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=3542119"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=3542119"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=3542119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}