{"id":380512,"date":"2023-02-16T14:54:52","date_gmt":"2016-05-12T14:24:36","guid":{"rendered":""},"modified":"2026-08-31T17:47:04","modified_gmt":"2026-08-31T17:47:04","slug":"6392083-citroen-jumper-2012-nockenwelle-zahnrad-0831v9","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/","title":{"rendered":"Citroen Jumper  Nockenwelle Zahnrad 2012 0831V9"},"content":{"rendered":"<p>Nockenwelle Zahnrad<\/p>\n","protected":false},"excerpt":{"rendered":"Nockenwelle Zahnrad","protected":false},"featured_media":1079490,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[243,270],"product_tag":[],"class_list":["post-380512","product","type-product","status-publish","has-post-thumbnail","product_cat-citroen","product_cat-jumper","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen Jumper Nockenwelle Zahnrad 2012 0831V9 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen Jumper Nockenwelle Zahnrad 2012 0831V9 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Nockenwelle Zahnrad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T17:47:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/02\/2ea2e34a-810f-4265-bda1-bc67f92c9952-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/\",\"name\":\"Citroen Jumper Nockenwelle Zahnrad 2012 0831V9 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/2ea2e34a-810f-4265-bda1-bc67f92c9952.jpg\",\"datePublished\":\"2016-05-12T14:24:36+00:00\",\"dateModified\":\"2026-08-31T17:47:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/2ea2e34a-810f-4265-bda1-bc67f92c9952.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/2ea2e34a-810f-4265-bda1-bc67f92c9952.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nockenwelle Zahnrad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen Jumper Nockenwelle Zahnrad 2012 0831V9 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/","og_locale":"de_DE","og_type":"article","og_title":"Citroen Jumper Nockenwelle Zahnrad 2012 0831V9 | De Vos Onderdelen","og_description":"Nockenwelle Zahnrad","og_url":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2026-08-31T17:47:04+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/02\/2ea2e34a-810f-4265-bda1-bc67f92c9952-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/","url":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/","name":"Citroen Jumper Nockenwelle Zahnrad 2012 0831V9 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/2ea2e34a-810f-4265-bda1-bc67f92c9952.jpg","datePublished":"2016-05-12T14:24:36+00:00","dateModified":"2026-08-31T17:47:04+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/2ea2e34a-810f-4265-bda1-bc67f92c9952.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/2ea2e34a-810f-4265-bda1-bc67f92c9952.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/citroen\/jumper\/6392083-nockenwelle-zahnrad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Nockenwelle Zahnrad"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/380512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/1079490"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=380512"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=380512"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=380512"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=380512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}