{"id":4059164,"date":"2026-03-21T11:27:13","date_gmt":"2026-03-21T09:42:36","guid":{"rendered":""},"modified":"2026-03-30T10:04:54","modified_gmt":"2026-03-30T10:04:54","slug":"24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/","title":{"rendered":"Peugeot 308 1.6 16V GTI Felge 2011 96770292XS"},"content":{"rendered":"<p>Felge<\/p>\n","protected":false},"excerpt":{"rendered":"Felge","protected":false},"featured_media":4061868,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[296,310],"product_tag":[],"class_list":["post-4059164","product","type-product","status-publish","has-post-thumbnail","product_cat-peugeot","product_cat-310","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 308 1.6 16V GTI Felge 2011 96770292XS | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 308 1.6 16V GTI Felge 2011 96770292XS | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Felge\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T10:04:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/\",\"name\":\"Peugeot 308 1.6 16V GTI Felge 2011 96770292XS | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/aea314cf-3ea3-4393-a9e2-e06ede04194e.jpg\",\"datePublished\":\"2026-03-21T09:42:36+00:00\",\"dateModified\":\"2026-03-30T10:04:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/aea314cf-3ea3-4393-a9e2-e06ede04194e.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/aea314cf-3ea3-4393-a9e2-e06ede04194e.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peugeot 308 1.6 16V GTI Felge 2011 96770292XS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 308 1.6 16V GTI Felge 2011 96770292XS | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/","og_locale":"de_DE","og_type":"article","og_title":"Peugeot 308 1.6 16V GTI Felge 2011 96770292XS | De Vos Onderdelen","og_description":"Felge","og_url":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2026-03-30T10:04:54+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/","url":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/","name":"Peugeot 308 1.6 16V GTI Felge 2011 96770292XS | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/aea314cf-3ea3-4393-a9e2-e06ede04194e.jpg","datePublished":"2026-03-21T09:42:36+00:00","dateModified":"2026-03-30T10:04:54+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/aea314cf-3ea3-4393-a9e2-e06ede04194e.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/aea314cf-3ea3-4393-a9e2-e06ede04194e.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/24756657-peugeot-308-1-6-16v-gti-2011-felge-96770292xs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Peugeot 308 1.6 16V GTI Felge 2011 96770292XS"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/4059164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/4061868"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=4059164"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=4059164"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=4059164"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=4059164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}