{"id":4103362,"date":"2026-05-18T22:39:41","date_gmt":"2026-05-18T20:21:39","guid":{"rendered":""},"modified":"2026-05-28T10:51:19","modified_gmt":"2026-05-28T10:51:19","slug":"25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/","title":{"rendered":"Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780"},"content":{"rendered":"<p>Sto\u00dfd\u00e4mpferstrebe rechts vorne<\/p>\n","protected":false},"excerpt":{"rendered":"Sto\u00dfd\u00e4mpferstrebe rechts vorne","protected":false},"featured_media":4106433,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[243,259],"product_tag":[],"class_list":["post-4103362","product","type-product","status-publish","has-post-thumbnail","product_cat-citroen","product_cat-c5-aircross","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Sto\u00dfd\u00e4mpferstrebe rechts vorne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T10:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/\",\"name\":\"Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/05\/937026b7-0b3e-4453-b670-a235cb7d9a89.jpg\",\"datePublished\":\"2026-05-18T20:21:39+00:00\",\"dateModified\":\"2026-05-28T10:51:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/05\/937026b7-0b3e-4453-b670-a235cb7d9a89.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/05\/937026b7-0b3e-4453-b670-a235cb7d9a89.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/","og_locale":"de_DE","og_type":"article","og_title":"Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780 | De Vos Onderdelen","og_description":"Sto\u00dfd\u00e4mpferstrebe rechts vorne","og_url":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2026-05-28T10:51:19+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/","url":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/","name":"Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/05\/937026b7-0b3e-4453-b670-a235cb7d9a89.jpg","datePublished":"2026-05-18T20:21:39+00:00","dateModified":"2026-05-28T10:51:19+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/05\/937026b7-0b3e-4453-b670-a235cb7d9a89.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/05\/937026b7-0b3e-4453-b670-a235cb7d9a89.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25109661-citroen-c5-aircross-1-2-e-thp-puretech-130-2019-stosdampferstrebe-rechts-vorne-9833696780\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Citroen C5 Aircross 1.2 e-THP PureTech 130 Sto\u00dfd\u00e4mpferstrebe rechts vorne 2019 9833696780"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/4103362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/4106433"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=4103362"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=4103362"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=4103362"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=4103362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}