{"id":4129423,"date":"2026-07-16T16:33:43","date_gmt":"2026-07-16T17:40:08","guid":{"rendered":""},"modified":"2026-08-31T21:03:19","modified_gmt":"2026-08-31T21:03:19","slug":"25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/","title":{"rendered":"Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180"},"content":{"rendered":"<p>Motorlager<\/p>\n","protected":false},"excerpt":{"rendered":"Motorlager","protected":false},"featured_media":4131591,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[243,270],"product_tag":[],"class_list":["post-4129423","product","type-product","status-publish","has-post-thumbnail","product_cat-citroen","product_cat-jumper","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Motorlager\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T21:03:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/\",\"name\":\"Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/07\/773161d3-ab4d-4570-95ed-e9d62094e4c8.jpg\",\"datePublished\":\"2026-07-16T17:40:08+00:00\",\"dateModified\":\"2026-08-31T21:03:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/07\/773161d3-ab4d-4570-95ed-e9d62094e4c8.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/07\/773161d3-ab4d-4570-95ed-e9d62094e4c8.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/","og_locale":"de_DE","og_type":"article","og_title":"Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180 | De Vos Onderdelen","og_description":"Motorlager","og_url":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2026-08-31T21:03:19+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/","url":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/","name":"Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/07\/773161d3-ab4d-4570-95ed-e9d62094e4c8.jpg","datePublished":"2026-07-16T17:40:08+00:00","dateModified":"2026-08-31T21:03:19+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/07\/773161d3-ab4d-4570-95ed-e9d62094e4c8.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/07\/773161d3-ab4d-4570-95ed-e9d62094e4c8.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/25596969-citroen-jumper-2-2-hdi-110-2013-motorlager-4h03-182136-1607759180\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Citroen Jumper 2.2 HDi 110 Motorlager 4H03 2013 182136-1607759180"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/4129423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/4131591"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=4129423"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=4129423"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=4129423"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=4129423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}