{"id":654709,"date":"2023-04-18T21:05:11","date_gmt":"2012-08-27T11:13:44","guid":{"rendered":""},"modified":"2025-09-03T14:36:10","modified_gmt":"2025-09-03T14:36:10","slug":"343896-peugeot-107-1-0-12v-2011-tacho-kombiinstrument-km","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/","title":{"rendered":"Peugeot 107 1.0 12V Tacho &#8211; Kombiinstrument KM 2011"},"content":{"rendered":"<p>Tacho &#8211; Kombiinstrument KM<\/p>\n","protected":false},"excerpt":{"rendered":"Tacho &#8211; Kombiinstrument KM","protected":false},"featured_media":1030933,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[299,296],"product_tag":[],"class_list":["post-654709","product","type-product","status-publish","has-post-thumbnail","product_cat-299","product_cat-peugeot","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 107 1.0 12V Tacho - Kombiinstrument KM 2011 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 107 1.0 12V Tacho - Kombiinstrument KM 2011 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Tacho &#8211; Kombiinstrument KM\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T14:36:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/337e344d-1c0b-4963-9b4a-c66b0b56acbd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/\",\"name\":\"Peugeot 107 1.0 12V Tacho - Kombiinstrument KM 2011 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/337e344d-1c0b-4963-9b4a-c66b0b56acbd.jpg\",\"datePublished\":\"2012-08-27T11:13:44+00:00\",\"dateModified\":\"2025-09-03T14:36:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/337e344d-1c0b-4963-9b4a-c66b0b56acbd.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/337e344d-1c0b-4963-9b4a-c66b0b56acbd.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tacho &#8211; Kombiinstrument KM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 107 1.0 12V Tacho - Kombiinstrument KM 2011 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/","og_locale":"de_DE","og_type":"article","og_title":"Peugeot 107 1.0 12V Tacho - Kombiinstrument KM 2011 | De Vos Onderdelen","og_description":"Tacho &#8211; Kombiinstrument KM","og_url":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-09-03T14:36:10+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/337e344d-1c0b-4963-9b4a-c66b0b56acbd.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/","url":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/","name":"Peugeot 107 1.0 12V Tacho - Kombiinstrument KM 2011 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/337e344d-1c0b-4963-9b4a-c66b0b56acbd.jpg","datePublished":"2012-08-27T11:13:44+00:00","dateModified":"2025-09-03T14:36:10+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/337e344d-1c0b-4963-9b4a-c66b0b56acbd.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/337e344d-1c0b-4963-9b4a-c66b0b56acbd.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/peugeot\/107\/343896-tacho-kombiinstrument-km\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Tacho &#8211; Kombiinstrument KM"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/654709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/1030933"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=654709"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=654709"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=654709"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=654709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}