{"id":778477,"date":"2023-04-19T05:12:34","date_gmt":"2010-11-25T15:05:02","guid":{"rendered":""},"modified":"2025-09-03T18:50:55","modified_gmt":"2025-09-03T18:50:55","slug":"1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/","title":{"rendered":"Citroen C5 2.0 HDi 110 Sicherheitsgurt rechts hinten 2002 8974KE"},"content":{"rendered":"<p>Sicherheitsgurt rechts hinten<\/p>\n","protected":false},"excerpt":{"rendered":"Sicherheitsgurt rechts hinten","protected":false},"featured_media":778470,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[243,258],"product_tag":[],"class_list":{"0":"post-778477","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-citroen","7":"product_cat-c5","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen C5 2.0 HDi 110 Sicherheitsgurt rechts hinten 2002 8974KE | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen C5 2.0 HDi 110 Sicherheitsgurt rechts hinten 2002 8974KE | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Sicherheitsgurt rechts hinten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T18:50:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/48b4767f-7732-4b2b-97f8-5f0844ee1d3d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/\",\"name\":\"Citroen C5 2.0 HDi 110 Sicherheitsgurt rechts hinten 2002 8974KE | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/48b4767f-7732-4b2b-97f8-5f0844ee1d3d.jpg\",\"datePublished\":\"2010-11-25T15:05:02+00:00\",\"dateModified\":\"2025-09-03T18:50:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/48b4767f-7732-4b2b-97f8-5f0844ee1d3d.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/48b4767f-7732-4b2b-97f8-5f0844ee1d3d.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Teile online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicherheitsgurt rechts hinten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen C5 2.0 HDi 110 Sicherheitsgurt rechts hinten 2002 8974KE | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/","og_locale":"de_DE","og_type":"article","og_title":"Citroen C5 2.0 HDi 110 Sicherheitsgurt rechts hinten 2002 8974KE | De Vos Onderdelen","og_description":"Sicherheitsgurt rechts hinten","og_url":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-09-03T18:50:55+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/48b4767f-7732-4b2b-97f8-5f0844ee1d3d.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/","url":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/","name":"Citroen C5 2.0 HDi 110 Sicherheitsgurt rechts hinten 2002 8974KE | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/48b4767f-7732-4b2b-97f8-5f0844ee1d3d.jpg","datePublished":"2010-11-25T15:05:02+00:00","dateModified":"2025-09-03T18:50:55+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/48b4767f-7732-4b2b-97f8-5f0844ee1d3d.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/48b4767f-7732-4b2b-97f8-5f0844ee1d3d.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/de\/product\/1477877-citroen-c5-2-0-hdi-110-2002-sicherheitsgurt-rechts-hinten-8974ke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Teile online","item":"https:\/\/www.devosautodemontage.nl\/de\/teile-online\/"},{"@type":"ListItem","position":2,"name":"Sicherheitsgurt rechts hinten"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/de\/#website","url":"https:\/\/www.devosautodemontage.nl\/de\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/de\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product\/778477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media\/778470"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/media?parent=778477"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_brand?post=778477"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_cat?post=778477"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/de\/wp-json\/wp\/v2\/product_tag?post=778477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}