{"id":295854,"date":"2023-02-16T08:34:23","date_gmt":"2023-01-17T10:46:58","guid":{"rendered":""},"modified":"2024-03-21T14:45:20","modified_gmt":"2024-03-21T14:45:20","slug":"17997971-peugeot-rcz-2014-airbag-module-9803594180","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/","title":{"rendered":"Peugeot RCZ  Airbag Module 2014 9803594180"},"content":{"rendered":"<p>Airbag Module<\/p>\n","protected":false},"excerpt":{"rendered":"Airbag Module","protected":false},"featured_media":898579,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[209,241],"product_tag":[],"class_list":["post-295854","product","type-product","status-publish","has-post-thumbnail","product_cat-peugeot","product_cat-rcz","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot RCZ Airbag Module 2014 9803594180 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot RCZ Airbag Module 2014 9803594180 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Airbag Module\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T14:45:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/02\/9bdc887c-708a-4d5e-bc01-72b756ef532c-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/\",\"name\":\"Peugeot RCZ Airbag Module 2014 9803594180 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/9bdc887c-708a-4d5e-bc01-72b756ef532c.jpg\",\"datePublished\":\"2023-01-17T10:46:58+00:00\",\"dateModified\":\"2024-03-21T14:45:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/9bdc887c-708a-4d5e-bc01-72b756ef532c.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/9bdc887c-708a-4d5e-bc01-72b756ef532c.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Airbag Module\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot RCZ Airbag Module 2014 9803594180 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/","og_locale":"en_US","og_type":"article","og_title":"Peugeot RCZ Airbag Module 2014 9803594180 | De Vos Onderdelen","og_description":"Airbag Module","og_url":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2024-03-21T14:45:20+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/02\/9bdc887c-708a-4d5e-bc01-72b756ef532c-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/","url":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/","name":"Peugeot RCZ Airbag Module 2014 9803594180 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/9bdc887c-708a-4d5e-bc01-72b756ef532c.jpg","datePublished":"2023-01-17T10:46:58+00:00","dateModified":"2024-03-21T14:45:20+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/9bdc887c-708a-4d5e-bc01-72b756ef532c.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/9bdc887c-708a-4d5e-bc01-72b756ef532c.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/rcz\/17997971-airbag-module\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Airbag Module"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/295854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/898579"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=295854"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=295854"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=295854"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=295854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}