{"id":3456379,"date":"2024-02-05T16:18:18","date_gmt":"2023-12-20T10:20:25","guid":{"rendered":""},"modified":"2025-10-28T13:53:39","modified_gmt":"2025-10-28T13:53:39","slug":"19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/","title":{"rendered":"Citroen C3 1.2 Vti 12V PureTech Engine management computer HMR 2020 1635070680-9830510980"},"content":{"rendered":"<p>Engine management computer<\/p>\n","protected":false},"excerpt":{"rendered":"Engine management computer","protected":false},"featured_media":2850458,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[156,164],"product_tag":[],"class_list":{"0":"post-3456379","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-citroen","7":"product_cat-c3","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen C3 1.2 Vti 12V PureTech Engine management computer HMR 2020 1635070680-9830510980 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen C3 1.2 Vti 12V PureTech Engine management computer HMR 2020 1635070680-9830510980 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Engine management computer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T13:53:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/12\/20c32a2d-1523-44de-bced-c7dafbeb7b15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/\",\"name\":\"Citroen C3 1.2 Vti 12V PureTech Engine management computer HMR 2020 1635070680-9830510980 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/12\/20c32a2d-1523-44de-bced-c7dafbeb7b15.jpg\",\"datePublished\":\"2023-12-20T10:20:25+00:00\",\"dateModified\":\"2025-10-28T13:53:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/12\/20c32a2d-1523-44de-bced-c7dafbeb7b15.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/12\/20c32a2d-1523-44de-bced-c7dafbeb7b15.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engine management computer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen C3 1.2 Vti 12V PureTech Engine management computer HMR 2020 1635070680-9830510980 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/","og_locale":"en_US","og_type":"article","og_title":"Citroen C3 1.2 Vti 12V PureTech Engine management computer HMR 2020 1635070680-9830510980 | De Vos Onderdelen","og_description":"Engine management computer","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-10-28T13:53:39+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/12\/20c32a2d-1523-44de-bced-c7dafbeb7b15.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/","name":"Citroen C3 1.2 Vti 12V PureTech Engine management computer HMR 2020 1635070680-9830510980 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/12\/20c32a2d-1523-44de-bced-c7dafbeb7b15.jpg","datePublished":"2023-12-20T10:20:25+00:00","dateModified":"2025-10-28T13:53:39+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/12\/20c32a2d-1523-44de-bced-c7dafbeb7b15.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/12\/20c32a2d-1523-44de-bced-c7dafbeb7b15.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/19866668-citroen-c3-1-2-vti-12v-puretech-2020-engine-management-computer-hmr-1635070680-9830510980\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Engine management computer"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/3456379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/2850458"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=3456379"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=3456379"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=3456379"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=3456379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}