{"id":3490244,"date":"2024-04-17T22:23:42","date_gmt":"2024-04-17T20:28:48","guid":{"rendered":""},"modified":"2025-05-05T17:04:38","modified_gmt":"2025-05-05T17:04:38","slug":"20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/","title":{"rendered":"Peugeot 3008 1.5 BlueHDi 130 Taillight, left 2023 9810477880"},"content":{"rendered":"<p>Taillight, left<\/p>\n","protected":false},"excerpt":{"rendered":"Taillight, left","protected":false},"featured_media":3490423,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[209,220],"product_tag":[],"class_list":["post-3490244","product","type-product","status-publish","has-post-thumbnail","product_cat-peugeot","product_cat-220","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 3008 1.5 BlueHDi 130 Taillight, left 2023 9810477880 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 3008 1.5 BlueHDi 130 Taillight, left 2023 9810477880 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Taillight, left\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T17:04:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/\",\"name\":\"Peugeot 3008 1.5 BlueHDi 130 Taillight, left 2023 9810477880 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/04\/e6266958-aa73-4852-9b0f-279fd103be14.jpg\",\"datePublished\":\"2024-04-17T20:28:48+00:00\",\"dateModified\":\"2025-05-05T17:04:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/04\/e6266958-aa73-4852-9b0f-279fd103be14.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/04\/e6266958-aa73-4852-9b0f-279fd103be14.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taillight, left\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 3008 1.5 BlueHDi 130 Taillight, left 2023 9810477880 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/","og_locale":"en_US","og_type":"article","og_title":"Peugeot 3008 1.5 BlueHDi 130 Taillight, left 2023 9810477880 | De Vos Onderdelen","og_description":"Taillight, left","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-05-05T17:04:38+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/","name":"Peugeot 3008 1.5 BlueHDi 130 Taillight, left 2023 9810477880 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/04\/e6266958-aa73-4852-9b0f-279fd103be14.jpg","datePublished":"2024-04-17T20:28:48+00:00","dateModified":"2025-05-05T17:04:38+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/04\/e6266958-aa73-4852-9b0f-279fd103be14.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/04\/e6266958-aa73-4852-9b0f-279fd103be14.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/20518080-peugeot-3008-1-5-bluehdi-130-2023-taillight-left-9810477880\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Taillight, left"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/3490244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/3490423"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=3490244"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=3490244"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=3490244"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=3490244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}