{"id":3551418,"date":"2024-10-16T16:31:08","date_gmt":"2024-09-26T13:11:11","guid":{"rendered":""},"modified":"2025-11-06T13:54:07","modified_gmt":"2025-11-06T13:54:07","slug":"21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/","title":{"rendered":"Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680"},"content":{"rendered":"<p>Catalytic converter<\/p>\n","protected":false},"excerpt":{"rendered":"Catalytic converter","protected":false},"featured_media":3547444,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[209,223],"product_tag":[],"class_list":{"0":"post-3551418","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-peugeot","7":"product_cat-223","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Catalytic converter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T13:54:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/10\/6f77f462-e94f-48ec-90b8-901b311592ea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/\",\"name\":\"Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/10\/6f77f462-e94f-48ec-90b8-901b311592ea.jpg\",\"datePublished\":\"2024-09-26T13:11:11+00:00\",\"dateModified\":\"2025-11-06T13:54:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/10\/6f77f462-e94f-48ec-90b8-901b311592ea.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/10\/6f77f462-e94f-48ec-90b8-901b311592ea.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/","og_locale":"en_US","og_type":"article","og_title":"Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680 | De Vos Onderdelen","og_description":"Catalytic converter","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-11-06T13:54:07+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/10\/6f77f462-e94f-48ec-90b8-901b311592ea.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/","name":"Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/10\/6f77f462-e94f-48ec-90b8-901b311592ea.jpg","datePublished":"2024-09-26T13:11:11+00:00","dateModified":"2025-11-06T13:54:07+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/10\/6f77f462-e94f-48ec-90b8-901b311592ea.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2024\/10\/6f77f462-e94f-48ec-90b8-901b311592ea.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/21326579-peugeot-308-1-2-12v-e-thp-puretech-110-2016-catalytic-converter-hnz-9812493680\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Peugeot 308 1.2 12V e-THP PureTech 110 Catalytic converter HNZ 2016 9812493680"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/3551418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/3547444"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=3551418"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=3551418"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=3551418"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=3551418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}