{"id":3603904,"date":"2025-03-24T23:25:58","date_gmt":"2025-03-24T20:50:58","guid":{"rendered":""},"modified":"2025-03-27T14:43:34","modified_gmt":"2025-03-27T14:43:34","slug":"22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/","title":{"rendered":"Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW"},"content":{"rendered":"<p>Sun visor<\/p>\n","protected":false},"excerpt":{"rendered":"Sun visor","protected":false},"featured_media":3604681,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[36472,209],"product_tag":[],"class_list":{"0":"post-3603904","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-36472","7":"product_cat-peugeot","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Sun visor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-27T14:43:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/\",\"name\":\"Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/03\/01e4f167-e36f-4d3b-b785-9c29d64c0686.jpg\",\"datePublished\":\"2025-03-24T20:50:58+00:00\",\"dateModified\":\"2025-03-27T14:43:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/03\/01e4f167-e36f-4d3b-b785-9c29d64c0686.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/03\/01e4f167-e36f-4d3b-b785-9c29d64c0686.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/","og_locale":"en_US","og_type":"article","og_title":"Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW | De Vos Onderdelen","og_description":"Sun visor","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-03-27T14:43:34+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/","name":"Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/03\/01e4f167-e36f-4d3b-b785-9c29d64c0686.jpg","datePublished":"2025-03-24T20:50:58+00:00","dateModified":"2025-03-27T14:43:34+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/03\/01e4f167-e36f-4d3b-b785-9c29d64c0686.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/03\/01e4f167-e36f-4d3b-b785-9c29d64c0686.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/22395399-peugeot-408-1-2-hybrid-136-2022-sun-visor-98173684uw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Peugeot 408 1.2 Hybrid 136 Sun visor 2022 98173684UW"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/3603904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/3604681"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=3603904"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=3603904"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=3603904"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=3603904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}