{"id":3729317,"date":"2025-12-03T23:23:36","date_gmt":"2025-12-03T15:44:56","guid":{"rendered":""},"modified":"2026-09-01T06:19:49","modified_gmt":"2026-09-01T06:19:49","slug":"24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/","title":{"rendered":"Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT"},"content":{"rendered":"<p>Front bumper<\/p>\n","protected":false},"excerpt":{"rendered":"Front bumper","protected":false},"featured_media":3730222,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[156,164],"product_tag":[],"class_list":["post-3729317","product","type-product","status-publish","has-post-thumbnail","product_cat-citroen","product_cat-c3","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Front bumper\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T06:19:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/\",\"name\":\"Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/12\/893793f7-1e40-491a-8e90-5d7c1877a2ca.jpg\",\"datePublished\":\"2025-12-03T15:44:56+00:00\",\"dateModified\":\"2026-09-01T06:19:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/12\/893793f7-1e40-491a-8e90-5d7c1877a2ca.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/12\/893793f7-1e40-491a-8e90-5d7c1877a2ca.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/","og_locale":"en_US","og_type":"article","og_title":"Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT | De Vos Onderdelen","og_description":"Front bumper","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2026-09-01T06:19:49+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/","name":"Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/12\/893793f7-1e40-491a-8e90-5d7c1877a2ca.jpg","datePublished":"2025-12-03T15:44:56+00:00","dateModified":"2026-09-01T06:19:49+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/12\/893793f7-1e40-491a-8e90-5d7c1877a2ca.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2025\/12\/893793f7-1e40-491a-8e90-5d7c1877a2ca.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24005963-citroen-c3-1-2-12v-e-thp-puretech-110-2019-front-bumper-1618082680-98120615xt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Citroen C3 1.2 12V e-THP PureTech 110 Front bumper 2019 1618082680-98120615XT"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/3729317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/3730222"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=3729317"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=3729317"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=3729317"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=3729317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}