{"id":4056449,"date":"2026-03-17T17:23:31","date_gmt":"2026-03-17T16:34:05","guid":{"rendered":""},"modified":"2026-03-30T10:04:55","modified_gmt":"2026-03-30T10:04:55","slug":"24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/","title":{"rendered":"Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0"},"content":{"rendered":"<p>Knuckle, front right<\/p>\n","protected":false},"excerpt":{"rendered":"Knuckle, front right","protected":false},"featured_media":4062362,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[209,223],"product_tag":[],"class_list":["post-4056449","product","type-product","status-publish","has-post-thumbnail","product_cat-peugeot","product_cat-223","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Knuckle, front right\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T10:04:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"663\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/\",\"name\":\"Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/8ffdbdbc-6c3a-4a3f-91f0-1195754b80c2.jpg\",\"datePublished\":\"2026-03-17T16:34:05+00:00\",\"dateModified\":\"2026-03-30T10:04:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/8ffdbdbc-6c3a-4a3f-91f0-1195754b80c2.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/8ffdbdbc-6c3a-4a3f-91f0-1195754b80c2.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/","og_locale":"en_US","og_type":"article","og_title":"Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0 | De Vos Onderdelen","og_description":"Knuckle, front right","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2026-03-30T10:04:55+00:00","og_image":[{"width":663,"height":278,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/","name":"Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/8ffdbdbc-6c3a-4a3f-91f0-1195754b80c2.jpg","datePublished":"2026-03-17T16:34:05+00:00","dateModified":"2026-03-30T10:04:55+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/8ffdbdbc-6c3a-4a3f-91f0-1195754b80c2.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2026\/03\/8ffdbdbc-6c3a-4a3f-91f0-1195754b80c2.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/24731466-peugeot-308-1-6-16v-gti-2011-knuckle-front-right-3647c0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Peugeot 308 1.6 16V GTI Knuckle, front right 2011 3647C0"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/4056449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/4062362"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=4056449"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=4056449"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=4056449"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=4056449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}