{"id":410421,"date":"2023-02-16T17:20:21","date_gmt":"2021-04-12T15:15:32","guid":{"rendered":""},"modified":"2025-09-03T11:27:14","modified_gmt":"2025-09-03T11:27:14","slug":"15038345-peugeot-3008-1-6-e-thp-165-16v-2018-front-wiper-arm-1617040080","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/","title":{"rendered":"Peugeot 3008 1.6 e-THP 165 16V Front wiper arm 2018 1617040080"},"content":{"rendered":"<p>Front wiper arm<\/p>\n","protected":false},"excerpt":{"rendered":"Front wiper arm","protected":false},"featured_media":1178392,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[209,220],"product_tag":[],"class_list":["post-410421","product","type-product","status-publish","has-post-thumbnail","product_cat-peugeot","product_cat-220","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 3008 1.6 e-THP 165 16V Front wiper arm 2018 1617040080 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 3008 1.6 e-THP 165 16V Front wiper arm 2018 1617040080 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Front wiper arm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T11:27:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/02\/8bb3f903-a9f3-43f9-b70a-473d7eeefadd-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/\",\"name\":\"Peugeot 3008 1.6 e-THP 165 16V Front wiper arm 2018 1617040080 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/8bb3f903-a9f3-43f9-b70a-473d7eeefadd.jpg\",\"datePublished\":\"2021-04-12T15:15:32+00:00\",\"dateModified\":\"2025-09-03T11:27:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/8bb3f903-a9f3-43f9-b70a-473d7eeefadd.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/8bb3f903-a9f3-43f9-b70a-473d7eeefadd.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Front wiper arm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 3008 1.6 e-THP 165 16V Front wiper arm 2018 1617040080 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/","og_locale":"en_US","og_type":"article","og_title":"Peugeot 3008 1.6 e-THP 165 16V Front wiper arm 2018 1617040080 | De Vos Onderdelen","og_description":"Front wiper arm","og_url":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-09-03T11:27:14+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/02\/8bb3f903-a9f3-43f9-b70a-473d7eeefadd-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/","url":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/","name":"Peugeot 3008 1.6 e-THP 165 16V Front wiper arm 2018 1617040080 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/8bb3f903-a9f3-43f9-b70a-473d7eeefadd.jpg","datePublished":"2021-04-12T15:15:32+00:00","dateModified":"2025-09-03T11:27:14+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/8bb3f903-a9f3-43f9-b70a-473d7eeefadd.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/11\/8bb3f903-a9f3-43f9-b70a-473d7eeefadd.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/peugeot\/3008\/15038345-front-wiper-arm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Front wiper arm"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/410421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/1178392"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=410421"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=410421"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=410421"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=410421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}