{"id":713454,"date":"2023-04-19T00:48:16","date_gmt":"2017-06-08T14:38:00","guid":{"rendered":""},"modified":"2025-09-03T19:07:04","modified_gmt":"2025-09-03T19:07:04","slug":"8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/","title":{"rendered":"Citroen Saxo 1.1i X,SX Front brake calliper, left HDZ 1999 4400K1-441003"},"content":{"rendered":"<p>Front brake calliper, left<\/p>\n","protected":false},"excerpt":{"rendered":"Front brake calliper, left","protected":false},"featured_media":713451,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[156,188],"product_tag":[],"class_list":{"0":"post-713454","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-citroen","7":"product_cat-saxo","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen Saxo 1.1i X,SX Front brake calliper, left HDZ 1999 4400K1-441003 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen Saxo 1.1i X,SX Front brake calliper, left HDZ 1999 4400K1-441003 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Front brake calliper, left\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T19:07:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/62f5dec5-adf4-4960-9347-0be73795584d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/\",\"name\":\"Citroen Saxo 1.1i X,SX Front brake calliper, left HDZ 1999 4400K1-441003 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/62f5dec5-adf4-4960-9347-0be73795584d.jpg\",\"datePublished\":\"2017-06-08T14:38:00+00:00\",\"dateModified\":\"2025-09-03T19:07:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/62f5dec5-adf4-4960-9347-0be73795584d.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/62f5dec5-adf4-4960-9347-0be73795584d.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Front brake calliper, left\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen Saxo 1.1i X,SX Front brake calliper, left HDZ 1999 4400K1-441003 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/","og_locale":"en_US","og_type":"article","og_title":"Citroen Saxo 1.1i X,SX Front brake calliper, left HDZ 1999 4400K1-441003 | De Vos Onderdelen","og_description":"Front brake calliper, left","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-09-03T19:07:04+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/62f5dec5-adf4-4960-9347-0be73795584d.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/","name":"Citroen Saxo 1.1i X,SX Front brake calliper, left HDZ 1999 4400K1-441003 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/62f5dec5-adf4-4960-9347-0be73795584d.jpg","datePublished":"2017-06-08T14:38:00+00:00","dateModified":"2025-09-03T19:07:04+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/62f5dec5-adf4-4960-9347-0be73795584d.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/62f5dec5-adf4-4960-9347-0be73795584d.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/8410610-citroen-saxo-1-1i-xsx-1999-front-brake-calliper-left-hdz-4400k1-441003\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Front brake calliper, left"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/713454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/713451"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=713454"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=713454"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=713454"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=713454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}