{"id":732270,"date":"2023-04-19T02:06:05","date_gmt":"2021-01-13T10:05:31","guid":{"rendered":""},"modified":"2025-09-03T13:51:42","modified_gmt":"2025-09-03T13:51:42","slug":"14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/","title":{"rendered":"Peugeot 308  Window mechanism 4-door, front left 2011 9221CW-9221GX-9675467480"},"content":{"rendered":"<p>Window mechanism 4-door, front left<\/p>\n","protected":false},"excerpt":{"rendered":"Window mechanism 4-door, front left","protected":false},"featured_media":732264,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[209,223],"product_tag":[],"class_list":["post-732270","product","type-product","status-publish","has-post-thumbnail","product_cat-peugeot","product_cat-223","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot 308 Window mechanism 4-door, front left 2011 9221CW-9221GX-9675467480 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot 308 Window mechanism 4-door, front left 2011 9221CW-9221GX-9675467480 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Window mechanism 4-door, front left\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T13:51:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/e2e24d03-a748-43ae-ba16-e666d68875e1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/\",\"name\":\"Peugeot 308 Window mechanism 4-door, front left 2011 9221CW-9221GX-9675467480 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/e2e24d03-a748-43ae-ba16-e666d68875e1.jpg\",\"datePublished\":\"2021-01-13T10:05:31+00:00\",\"dateModified\":\"2025-09-03T13:51:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/e2e24d03-a748-43ae-ba16-e666d68875e1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/e2e24d03-a748-43ae-ba16-e666d68875e1.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Window mechanism 4-door, front left\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot 308 Window mechanism 4-door, front left 2011 9221CW-9221GX-9675467480 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/","og_locale":"en_US","og_type":"article","og_title":"Peugeot 308 Window mechanism 4-door, front left 2011 9221CW-9221GX-9675467480 | De Vos Onderdelen","og_description":"Window mechanism 4-door, front left","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-09-03T13:51:42+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/e2e24d03-a748-43ae-ba16-e666d68875e1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/","name":"Peugeot 308 Window mechanism 4-door, front left 2011 9221CW-9221GX-9675467480 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/e2e24d03-a748-43ae-ba16-e666d68875e1.jpg","datePublished":"2021-01-13T10:05:31+00:00","dateModified":"2025-09-03T13:51:42+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/e2e24d03-a748-43ae-ba16-e666d68875e1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/e2e24d03-a748-43ae-ba16-e666d68875e1.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/14449084-peugeot-308-2011-window-mechanism-4-door-front-left-9221cw-9221gx-9675467480\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Window mechanism 4-door, front left"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/732270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/732264"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=732270"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=732270"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=732270"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=732270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}