{"id":771864,"date":"2023-04-19T04:38:41","date_gmt":"2010-11-25T15:05:31","guid":{"rendered":""},"modified":"2025-09-03T18:50:54","modified_gmt":"2025-09-03T18:50:54","slug":"1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/","title":{"rendered":"Citroen C5 2.0 HDi 110 Rear seatbelt, left 2002 8974KE"},"content":{"rendered":"<p>Rear seatbelt, left<\/p>\n","protected":false},"excerpt":{"rendered":"Rear seatbelt, left","protected":false},"featured_media":771858,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[17452,156,171],"product_tag":[],"class_list":{"0":"post-771864","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-geen-categorie","7":"product_cat-citroen","8":"product_cat-c5","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citroen C5 2.0 HDi 110 Rear seatbelt, left 2002 8974KE | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citroen C5 2.0 HDi 110 Rear seatbelt, left 2002 8974KE | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Rear seatbelt, left\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T18:50:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/f8399741-77f5-416e-98e5-5440fd0f37f4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/\",\"name\":\"Citroen C5 2.0 HDi 110 Rear seatbelt, left 2002 8974KE | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/f8399741-77f5-416e-98e5-5440fd0f37f4.jpg\",\"datePublished\":\"2010-11-25T15:05:31+00:00\",\"dateModified\":\"2025-09-03T18:50:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/f8399741-77f5-416e-98e5-5440fd0f37f4.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/f8399741-77f5-416e-98e5-5440fd0f37f4.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rear seatbelt, left\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citroen C5 2.0 HDi 110 Rear seatbelt, left 2002 8974KE | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/","og_locale":"en_US","og_type":"article","og_title":"Citroen C5 2.0 HDi 110 Rear seatbelt, left 2002 8974KE | De Vos Onderdelen","og_description":"Rear seatbelt, left","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-09-03T18:50:54+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/f8399741-77f5-416e-98e5-5440fd0f37f4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/","name":"Citroen C5 2.0 HDi 110 Rear seatbelt, left 2002 8974KE | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/f8399741-77f5-416e-98e5-5440fd0f37f4.jpg","datePublished":"2010-11-25T15:05:31+00:00","dateModified":"2025-09-03T18:50:54+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/f8399741-77f5-416e-98e5-5440fd0f37f4.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/f8399741-77f5-416e-98e5-5440fd0f37f4.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/1477491-citroen-c5-2-0-hdi-110-2002-rear-seatbelt-left-8974ke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Rear seatbelt, left"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/771864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/771858"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=771864"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=771864"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=771864"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=771864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}