{"id":800763,"date":"2023-04-19T07:23:53","date_gmt":"2018-11-22T14:47:01","guid":{"rendered":""},"modified":"2025-09-03T14:51:21","modified_gmt":"2025-09-03T14:51:21","slug":"10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19","status":"publish","type":"product","link":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/","title":{"rendered":"Peugeot RCZ  Gearbox 5FV5F02 2010 2231G8-2232G1 20EA19"},"content":{"rendered":"<p>Gearbox<\/p>\n","protected":false},"excerpt":{"rendered":"Gearbox","protected":false},"featured_media":800754,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[209,241],"product_tag":[],"class_list":{"0":"post-800763","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-peugeot","7":"product_cat-rcz","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peugeot RCZ Gearbox 5FV5F02 2010 2231G8-2232G1 20EA19 | De Vos Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peugeot RCZ Gearbox 5FV5F02 2010 2231G8-2232G1 20EA19 | De Vos Onderdelen\" \/>\n<meta property=\"og:description\" content=\"Gearbox\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/\" \/>\n<meta property=\"og:site_name\" content=\"De Vos Autodemontage\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/devosautodemontage\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T14:51:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/193f430d-9a6c-42b1-ba1a-557735ed2898.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/\",\"name\":\"Peugeot RCZ Gearbox 5FV5F02 2010 2231G8-2232G1 20EA19 | De Vos Onderdelen\",\"isPartOf\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/193f430d-9a6c-42b1-ba1a-557735ed2898.jpg\",\"datePublished\":\"2018-11-22T14:47:01+00:00\",\"dateModified\":\"2025-09-03T14:51:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#primaryimage\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/193f430d-9a6c-42b1-ba1a-557735ed2898.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/193f430d-9a6c-42b1-ba1a-557735ed2898.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Parts online\",\"item\":\"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gearbox\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#website\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"name\":\"De Vos Onderdelen\",\"description\":\"Peugeot - Citro\u00ebn \u2013 DS Automobiles\",\"publisher\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#organization\",\"name\":\"De Vos Onderdelen\",\"url\":\"https:\/\/www.devosautodemontage.nl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"contentUrl\":\"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg\",\"width\":663,\"height\":278,\"caption\":\"De Vos Onderdelen\"},\"image\":{\"@id\":\"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/devosautodemontage\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peugeot RCZ Gearbox 5FV5F02 2010 2231G8-2232G1 20EA19 | De Vos Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/","og_locale":"en_US","og_type":"article","og_title":"Peugeot RCZ Gearbox 5FV5F02 2010 2231G8-2232G1 20EA19 | De Vos Onderdelen","og_description":"Gearbox","og_url":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/","og_site_name":"De Vos Autodemontage","article_publisher":"https:\/\/www.facebook.com\/devosautodemontage","article_modified_time":"2025-09-03T14:51:21+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/193f430d-9a6c-42b1-ba1a-557735ed2898.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/","url":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/","name":"Peugeot RCZ Gearbox 5FV5F02 2010 2231G8-2232G1 20EA19 | De Vos Onderdelen","isPartOf":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#primaryimage"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/193f430d-9a6c-42b1-ba1a-557735ed2898.jpg","datePublished":"2018-11-22T14:47:01+00:00","dateModified":"2025-09-03T14:51:21+00:00","breadcrumb":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#primaryimage","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/193f430d-9a6c-42b1-ba1a-557735ed2898.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/193f430d-9a6c-42b1-ba1a-557735ed2898.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.devosautodemontage.nl\/en\/product\/10746549-peugeot-rcz-2010-gearbox-5fv5f02-2231g8-2232g1-20ea19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Parts online","item":"https:\/\/www.devosautodemontage.nl\/en\/parts-online\/"},{"@type":"ListItem","position":2,"name":"Gearbox"}]},{"@type":"WebSite","@id":"https:\/\/www.devosautodemontage.nl\/en\/#website","url":"https:\/\/www.devosautodemontage.nl\/en\/","name":"De Vos Onderdelen","description":"Peugeot - Citro\u00ebn \u2013 DS Automobiles","publisher":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devosautodemontage.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.devosautodemontage.nl\/en\/#organization","name":"De Vos Onderdelen","url":"https:\/\/www.devosautodemontage.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","contentUrl":"https:\/\/www.devosautodemontage.nl\/wp-content\/uploads\/2023\/04\/logo-1.jpg","width":663,"height":278,"caption":"De Vos Onderdelen"},"image":{"@id":"https:\/\/www.devosautodemontage.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/devosautodemontage"]}]}},"_links":{"self":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product\/800763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media\/800754"}],"wp:attachment":[{"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/media?parent=800763"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_brand?post=800763"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_cat?post=800763"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.devosautodemontage.nl\/en\/wp-json\/wp\/v2\/product_tag?post=800763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}